{"id":171296,"date":"2024-11-21T14:58:52","date_gmt":"2024-11-21T13:58:52","guid":{"rendered":"https:\/\/www.eliassen.nl\/service\/"},"modified":"2025-01-20T11:10:59","modified_gmt":"2025-01-20T10:10:59","slug":"service","status":"publish","type":"page","link":"https:\/\/dev.eliassen.nl\/en\/service\/","title":{"rendered":"Service"},"content":{"rendered":"<section id=\"block_35c63124d76bc0662e190950301a5910\" class=\"block block--content\">\n                <div class=\"block__inner \">\n                <div class=\"block__content\">\n        <p><span style=\"color: #ff0000;\">CALL OR MAIL US IF YOU WANT TO VISIT FOR A SPECIFIC<\/span><br \/>\n<span style=\"color: #ff0000;\">ARTICLE TO PREVENT THAT YOU COME FOR NOTHING!<\/span><\/p>\n<p>Feel free to ask for additional product photos!<br \/>\nWe have almost everything!<\/p>\n<p>Home &amp; Gardenpleasure Eliassen<br \/>\nHaarstraat 44<br \/>\n5324AP Ammerzoden, The Netherlands<br \/>\nTel : +031(0)73-5992869<\/p>\n            <\/div>\n    <\/div>\n    <\/section><section id=\"block_4cf227d5d2032d0023f238139cfd6574\" class=\"block block--columns block--spacing\">\n                <div class=\"block__inner \">\n            <div class=\"block__columns  block__columns--2\">\n      <div class=\"block__column \">\n                    <div class=\"block__content\">\n              <p>Opening hours November 2024<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-165939\" src=\"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/11\/Openingstijden-november-2024-Eliassen.nl_-300x203.png\" alt=\"\" width=\"450\" height=\"305\" srcset=\"https:\/\/dev.eliassen.nl\/wp-content\/uploads\/2024\/11\/Openingstijden-november-2024-Eliassen.nl_-300x203.png 300w, https:\/\/dev.eliassen.nl\/wp-content\/uploads\/2024\/11\/Openingstijden-november-2024-Eliassen.nl_-320x217.png 320w, https:\/\/dev.eliassen.nl\/wp-content\/uploads\/2024\/11\/Openingstijden-november-2024-Eliassen.nl_-600x406.png 600w, https:\/\/dev.eliassen.nl\/wp-content\/uploads\/2024\/11\/Openingstijden-november-2024-Eliassen.nl_-768x520.png 768w, https:\/\/dev.eliassen.nl\/wp-content\/uploads\/2024\/11\/Openingstijden-november-2024-Eliassen.nl_.png 970w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/p>\n          <\/div>\n      <\/div>\n      <div class=\"block__column \">\n                    <div class=\"block__content\">\n              <p>Opening hours December 2024<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-165960\" src=\"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/11\/Openingstijden-eliassen-december-2024-300x261.jpg\" alt=\"\" width=\"450\" height=\"392\" srcset=\"https:\/\/dev.eliassen.nl\/wp-content\/uploads\/2024\/11\/Openingstijden-eliassen-december-2024-300x261.jpg 300w, https:\/\/dev.eliassen.nl\/wp-content\/uploads\/2024\/11\/Openingstijden-eliassen-december-2024-320x278.jpg 320w, https:\/\/dev.eliassen.nl\/wp-content\/uploads\/2024\/11\/Openingstijden-eliassen-december-2024-600x522.jpg 600w, https:\/\/dev.eliassen.nl\/wp-content\/uploads\/2024\/11\/Openingstijden-eliassen-december-2024-768x668.jpg 768w, https:\/\/dev.eliassen.nl\/wp-content\/uploads\/2024\/11\/Openingstijden-eliassen-december-2024.jpg 909w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/p>\n          <\/div>\n      <\/div>\n              <\/div>\n    <\/div>\n    <\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-171296","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Service - Eliassen.nl<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Service - Eliassen.nl\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.eliassen.nl\/en\/service\/\" \/>\n<meta property=\"og:site_name\" content=\"Eliassen.nl\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TuincentrumEliassenAmmerzoden\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-20T10:10:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.eliassen.nl\/en\/service\/\",\"url\":\"https:\/\/dev.eliassen.nl\/en\/service\/\",\"name\":\"Service - Eliassen.nl\",\"isPartOf\":{\"@id\":\"https:\/\/dev.eliassen.nl\/en\/#website\"},\"datePublished\":\"2024-11-21T13:58:52+00:00\",\"dateModified\":\"2025-01-20T10:10:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.eliassen.nl\/en\/service\/#breadcrumb\"},\"inLanguage\":\"en-EN\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.eliassen.nl\/en\/service\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.eliassen.nl\/en\/service\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dev.eliassen.nl\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Service\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.eliassen.nl\/en\/#website\",\"url\":\"https:\/\/dev.eliassen.nl\/en\/\",\"name\":\"Eliassen Home & Garden Pleasure\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/dev.eliassen.nl\/en\/#organization\"},\"alternateName\":\"Eliassen.nl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.eliassen.nl\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-EN\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.eliassen.nl\/en\/#organization\",\"name\":\"Eliassen Home & Garden Pleasure\",\"url\":\"https:\/\/dev.eliassen.nl\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-EN\",\"@id\":\"https:\/\/dev.eliassen.nl\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/logo_4nd.jpg\",\"contentUrl\":\"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/logo_4nd.jpg\",\"width\":500,\"height\":500,\"caption\":\"Eliassen Home & Garden Pleasure\"},\"image\":{\"@id\":\"https:\/\/dev.eliassen.nl\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/TuincentrumEliassenAmmerzoden\",\"https:\/\/www.instagram.com\/eliassenhomeandgarden\/\",\"https:\/\/nl.pinterest.com\/eliassenhomeandgarden\/\",\"https:\/\/www.youtube.com\/@eliassenhomegardenpleasure4558\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Service - Eliassen.nl","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Service - Eliassen.nl","og_url":"https:\/\/dev.eliassen.nl\/en\/service\/","og_site_name":"Eliassen.nl","article_publisher":"https:\/\/www.facebook.com\/TuincentrumEliassenAmmerzoden","article_modified_time":"2025-01-20T10:10:59+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dev.eliassen.nl\/en\/service\/","url":"https:\/\/dev.eliassen.nl\/en\/service\/","name":"Service - Eliassen.nl","isPartOf":{"@id":"https:\/\/dev.eliassen.nl\/en\/#website"},"datePublished":"2024-11-21T13:58:52+00:00","dateModified":"2025-01-20T10:10:59+00:00","breadcrumb":{"@id":"https:\/\/dev.eliassen.nl\/en\/service\/#breadcrumb"},"inLanguage":"en-EN","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.eliassen.nl\/en\/service\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.eliassen.nl\/en\/service\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dev.eliassen.nl\/en\/"},{"@type":"ListItem","position":2,"name":"Service"}]},{"@type":"WebSite","@id":"https:\/\/dev.eliassen.nl\/en\/#website","url":"https:\/\/dev.eliassen.nl\/en\/","name":"Eliassen Home & Garden Pleasure","description":"","publisher":{"@id":"https:\/\/dev.eliassen.nl\/en\/#organization"},"alternateName":"Eliassen.nl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.eliassen.nl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-EN"},{"@type":"Organization","@id":"https:\/\/dev.eliassen.nl\/en\/#organization","name":"Eliassen Home & Garden Pleasure","url":"https:\/\/dev.eliassen.nl\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-EN","@id":"https:\/\/dev.eliassen.nl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/logo_4nd.jpg","contentUrl":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/logo_4nd.jpg","width":500,"height":500,"caption":"Eliassen Home & Garden Pleasure"},"image":{"@id":"https:\/\/dev.eliassen.nl\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TuincentrumEliassenAmmerzoden","https:\/\/www.instagram.com\/eliassenhomeandgarden\/","https:\/\/nl.pinterest.com\/eliassenhomeandgarden\/","https:\/\/www.youtube.com\/@eliassenhomegardenpleasure4558"]}]}},"_links":{"self":[{"href":"https:\/\/dev.eliassen.nl\/en\/wp-json\/wp\/v2\/pages\/171296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.eliassen.nl\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dev.eliassen.nl\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dev.eliassen.nl\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.eliassen.nl\/en\/wp-json\/wp\/v2\/comments?post=171296"}],"version-history":[{"count":1,"href":"https:\/\/dev.eliassen.nl\/en\/wp-json\/wp\/v2\/pages\/171296\/revisions"}],"predecessor-version":[{"id":171298,"href":"https:\/\/dev.eliassen.nl\/en\/wp-json\/wp\/v2\/pages\/171296\/revisions\/171298"}],"wp:attachment":[{"href":"https:\/\/dev.eliassen.nl\/en\/wp-json\/wp\/v2\/media?parent=171296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}